{"id":1979,"date":"2020-02-05T10:36:45","date_gmt":"2020-02-05T10:36:45","guid":{"rendered":"http:\/\/gear-coupling.top\/factory-direct-wholesale-coupling-pump-motor-special-coupling-gear-type-elastic-coupling-professional-quality\/"},"modified":"2020-02-05T10:36:45","modified_gmt":"2020-02-05T10:36:45","slug":"factory-direct-wholesale-coupling-pump-motor-special-coupling-gear-type-elastic-coupling-professional-quality","status":"publish","type":"post","link":"https:\/\/gear-coupling.top\/es\/application\/factory-direct-wholesale-coupling-pump-motor-special-coupling-gear-type-elastic-coupling-professional-quality\/","title":{"rendered":"Factory direct wholesale coupling pump motor special coupling gear type elastic coupling professional quality"},"content":{"rendered":"<div>\n<div>\n<div>\n<div><\/div>\n<div>\n<div>\n<div>Overview<\/div>\n<div>\n<div>\n<div>\n<div>Quick Details<\/div>\n<div>\n<dt class=\"do-entry-item\">\n                    <span>Place of Origin:<\/span>\n                <\/dt>\n<dd class=\"do-entry-item-val\">\n<div>Shandong, China<\/div>\n<\/dd>\n<dt class=\"do-entry-item\">\n                    <span>Brand Name:<\/span>\n                <\/dt>\n<dd class=\"do-entry-item-val\">\n<div>Haweisi<\/div>\n<\/dd>\n<dt class=\"do-entry-item\">\n                    <span>Type:<\/span>\n                <\/dt>\n<dd class=\"do-entry-item-val\">\n<div>Fittings<\/div>\n<\/dd>\n<dt class=\"do-entry-item\">\n                    <span>Product name:<\/span>\n                <\/dt>\n<dd class=\"do-entry-item-val\">\n<div>Flexible gear coupling<\/div>\n<\/dd>\n<dt class=\"do-entry-item\">\n                    <span>Brand:<\/span>\n                <\/dt>\n<dd class=\"do-entry-item-val\">\n<div>Haweisi<\/div>\n<\/dd>\n<dt class=\"do-entry-item\">\n                    <span>Warranty:<\/span>\n                <\/dt>\n<dd class=\"do-entry-item-val\">\n<div>1 Year<\/div>\n<\/dd>\n<dt class=\"do-entry-item\">\n                    <span>Package:<\/span>\n                <\/dt>\n<dd class=\"do-entry-item-val\">\n<div>Cartons or wooden cases<\/div>\n<\/dd>\n<dt class=\"do-entry-item\">\n                    <span>Certificate:<\/span>\n                <\/dt>\n<dd class=\"do-entry-item-val\">\n<div>ISO9001:2015<\/div>\n<\/dd>\n<dt class=\"do-entry-item\">\n                    <span>Usage:<\/span>\n                <\/dt>\n<dd class=\"do-entry-item-val\">\n<div>connect screw and shaft<\/div>\n<\/dd>\n<dt class=\"do-entry-item\">\n                    <span>Standard or Nonstandard:<\/span>\n                <\/dt>\n<dd class=\"do-entry-item-val\">\n<div>Standanrd(NL2-NL9)<\/div>\n<\/dd>\n<dt class=\"do-entry-item\">\n                    <span>N0n-standard products:<\/span>\n                <\/dt>\n<dd class=\"do-entry-item-val\">\n<div>can be customized<\/div>\n<\/dd><\/div>\n<\/div>\n<div>\n<div>Supply Ability<\/div>\n<div>\n<dt class=\"do-entry-item-key\" title=\"\">\n                    Supply Ability:\n                <\/dt>\n<dd class=\"do-entry-item-val\" title=\"5000 Piece\/Pieces per   Month\">5000 Piece\/Pieces per   Month<\/dd>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n<div>Packaging &amp; Delivery<\/div>\n<div>\n<dt class=\"do-entry-item-key\" title=\"Packaging Details\">Packaging Details<\/dt>\n<dd class=\"do-entry-item-val\" title=\"Carton and wooden case\">Carton and wooden case<\/dd>\n<dt class=\"do-entry-item-key\" title=\"Port\">Port<\/dt>\n<dd class=\"do-entry-item-val\" title=\"QINGDAO SHANGHAI\">QINGDAO SHANGHAI<\/dd>\n<dt class=\"do-entry-item-key\" title=\"Picture Example: \">\n                        Picture Example:\n                    <\/dt>\n<dd class=\"do-entry-item-val\">\n<div>\n<p>                                                                <span><\/span>\n                            <\/div>\n<div>\n<p>                                                                <span><\/span>\n                            <\/div>\n<\/dd>\n<dt class=\"name mk-name\" title=\"Lead Time\">\n                        Lead Time<br \/>\n                        :\n                    <\/dt>\n<dd class=\"do-entry-item-val\" title=\"Lead Time\">\n<td>Quantity(Pieces)<\/td>\n<td>1 &#8211; 100<\/td>\n<td>101 &#8211; 500<\/td>\n<td> &gt;500<\/td>\n<td>Est <\/p>\n<div>\n<div>\n<div><span>Product Description<\/span><\/div>\n<div>\n<td style=\"width: 77px;text-align: center\">Model<\/td>\n<td style=\"width: 98px;text-align: center\">\n<p>Nominal Torqu<\/p>\n<p>eTn(N.m)<\/p>\n<\/td>\n<td style=\"width: 98px;text-align: center\">\n<p>Permissible<\/p>\n<p>Speed<\/p>\n<p>(n)(t\/min)<\/p>\n<\/td>\n<td style=\"width: 81px;text-align: center\">\n<p>Axle hole diameter<\/p>\n<p>d1 d2<\/p>\n<\/td>\n<td style=\"width: 80px;text-align: center\">\n<p>Axle Hole<\/p>\n<p>Length<\/p>\n<p>L1 L2<\/p>\n<\/td>\n<td style=\"width: 24px;text-align: center\">D<\/td>\n<td style=\"width: 22px;text-align: center\">S<\/td>\n<td style=\"width: 31px;text-align: center\">L3<\/td>\n<td style=\"width: 102px;text-align: center\" colspan=\"3\">Allowable compensation<\/td>\n<td style=\"width: 39px;text-align: center\">\n<p>Moment<\/p>\n<p>of inertia<\/p>\n<p>(kg.m2)<\/p>\n<\/td>\n<td style=\"width: 45px;text-align: center\">\n<p>weight<\/p>\n<p>(kg)<\/p>\n<\/td>\n<td style=\"width: 77px;text-align: center\">NL2<\/td>\n<td style=\"width: 98px;text-align: center\">100<\/td>\n<td style=\"width: 98px;text-align: center\" rowspan=\"3\">6000<\/td>\n<td style=\"width: 81px;text-align: center\">\n<p>10.12.14.16<\/p>\n<p>18.20.22.24<\/p>\n<\/td>\n<td style=\"width: 80px;text-align: center\">\n<p>25.32<\/p>\n<p>42.52<\/p>\n<\/td>\n<td style=\"width: 24px;text-align: center\">55<\/td>\n<td style=\"width: 22px;text-align: center\" rowspan=\"7\">4<\/td>\n<td style=\"width: 31px;text-align: center\">40<\/td>\n<td style=\"width: 33px;text-align: center\" rowspan=\"3\">2<\/td>\n<td style=\"width: 35px;text-align: center\" rowspan=\"5\">\n<p>+<\/p>\n<p>-0.4<\/p>\n<\/td>\n<td style=\"width: 34px;text-align: center\" rowspan=\"3\">1<\/td>\n<td style=\"width: 39px;text-align: center\">0.92<\/td>\n<td style=\"width: 45px;text-align: center\">1.7<\/td>\n<td style=\"width: 77px;text-align: center\"><span>NL3<\/span><\/td>\n<td style=\"width: 98px;text-align: center\">160<\/td>\n<td style=\"width: 81px;text-align: center\">\n<p>20.22.24.25.28<\/p>\n<\/td>\n<td style=\"width: 80px;text-align: center\">52.62<\/td>\n<td style=\"width: 24px;text-align: center\">68<\/td>\n<td style=\"width: 31px;text-align: center\">46<\/td>\n<td style=\"width: 39px;text-align: center\">3.10<\/td>\n<td style=\"width: 45px;text-align: center\">2.6<\/td>\n<td style=\"width: 77px;text-align: center\"><span>NL4<\/span><\/td>\n<td style=\"width: 98px;text-align: center\">250<\/td>\n<td style=\"width: 81px;text-align: center\">28.30.32.35.38<\/td>\n<td style=\"width: 80px;text-align: center\">62.82<\/td>\n<td style=\"width: 24px;text-align: center\">85<\/td>\n<td style=\"width: 31px;text-align: center\">48<\/td>\n<td style=\"width: 39px;text-align: center\">8.69<\/td>\n<td style=\"width: 45px;text-align: center\">3.6<\/td>\n<td style=\"width: 77px;text-align: center\"><span>NL5<\/span><\/td>\n<td style=\"width: 98px;text-align: center\">315<\/td>\n<td style=\"width: 98px;text-align: center\" rowspan=\"2\">5000<\/td>\n<td style=\"width: 81px;text-align: center\">30.35.38.40.42<\/td>\n<td style=\"width: 80px;text-align: center\">82.112<\/td>\n<td style=\"width: 24px;text-align: center\">96<\/td>\n<td style=\"width: 31px;text-align: center\">50<\/td>\n<td style=\"width: 33px;text-align: center\" rowspan=\"2\">3<\/td>\n<td style=\"width: 33px;text-align: center\" rowspan=\"2\">2<\/td>\n<td style=\"width: 39px;text-align: center\">14.28<\/td>\n<td style=\"width: 45px;text-align: center\">5.4<\/td>\n<td style=\"width: 77px;text-align: center\"><span>NL6<\/span><\/td>\n<td style=\"width: 98px;text-align: center\">400<\/td>\n<td style=\"width: 81px;text-align: center\">40.42.45.48<\/td>\n<td style=\"width: 80px;text-align: center\">112<\/td>\n<td style=\"width: 24px;text-align: center\">10<\/td>\n<td style=\"width: 31px;text-align: center\">53<\/td>\n<td style=\"width: 39px;text-align: center\">18.34<\/td>\n<td style=\"width: 45px;text-align: center\">6.9<\/td>\n<td style=\"width: 77px;text-align: center\"><span>NL7<\/span><\/td>\n<td style=\"width: 98px;text-align: center\">630<\/td>\n<td style=\"width: 98px;text-align: center\" rowspan=\"2\">3600<\/td>\n<td style=\"width: 81px;text-align: center\">45.48.50.55<\/td>\n<td style=\"width: 80px;text-align: center\">112<\/td>\n<td style=\"width: 24px;text-align: center\">\n<p>11<\/p>\n<p>5<\/p>\n<\/td>\n<td style=\"width: 31px;text-align: center\">60<\/td>\n<td style=\"width: 33px;text-align: center\" rowspan=\"2\"><\/td>\n<td style=\"width: 35px;text-align: center\" rowspan=\"2\">\n<p>+<\/p>\n<p>-0.6<\/p>\n<\/td>\n<td style=\"width: 34px;text-align: center\" rowspan=\"4\"><\/td>\n<td style=\"width: 39px;text-align: center\">56.50<\/td>\n<td style=\"width: 45px;text-align: center\">9.8<\/td>\n<td style=\"width: 77px;text-align: center\"><span>NL8<\/span><\/td>\n<td style=\"width: 98px;text-align: center\">1250<\/td>\n<td style=\"width: 81px;text-align: center\">48.50.55.60.63.65<\/td>\n<td style=\"width: 80px;text-align: center\">112.142<\/td>\n<td style=\"width: 24px;text-align: center\">\n<p>14<\/p>\n<p>1<\/p>\n<\/td>\n<td style=\"width: 31px;text-align: center\">72<\/td>\n<td style=\"width: 39px;text-align: center\">98.55<\/td>\n<td style=\"width: 45px;text-align: center\">26.5<\/td>\n<td style=\"width: 77px;text-align: center\"><span>NL9<\/span><\/td>\n<td style=\"width: 98px;text-align: center\">2000<\/td>\n<td style=\"width: 98px;text-align: center\">2000<\/td>\n<td style=\"width: 81px;text-align: center\">\n<p>60.63.65.70.71.75.<\/p>\n<p>80<\/p>\n<\/td>\n<td style=\"width: 80px;text-align: center\">142.172<\/td>\n<td style=\"width: 24px;text-align: center\">\n<p>17<\/p>\n<p>5<\/p>\n<\/td>\n<td style=\"width: 22px;text-align: center\">6<\/td>\n<td style=\"width: 31px;text-align: center\">93<\/td>\n<td style=\"width: 33px;text-align: center\" rowspan=\"2\">4<\/td>\n<td style=\"width: 35px;text-align: center\" rowspan=\"2\">\n<p>+<\/p>\n<p>-0.7<\/p>\n<\/td>\n<td style=\"width: 39px;text-align: center\">370.50<\/td>\n<td style=\"width: 45px;text-align: center\">37.5<\/td>\n<td style=\"width: 77px;text-align: center\"><span>NL10<\/span><\/td>\n<td style=\"width: 98px;text-align: center\">3150<\/td>\n<td style=\"width: 98px;text-align: center\">1800<\/td>\n<td style=\"width: 81px;text-align: center\">\n<p>70.71.80.85<\/p>\n<p>90.95.100<\/p>\n<\/td>\n<td style=\"width: 80px;text-align: center\">\n<p>142.172<\/p>\n<p>212<\/p>\n<\/td>\n<td style=\"width: 24px;text-align: center\">\n<p>22<\/p>\n<p>0<\/p>\n<\/td>\n<td style=\"width: 22px;text-align: center\">8<\/td>\n<td style=\"width: 31px;text-align: center\">\n<p>11<\/p>\n<p>0<\/p>\n<\/td>\n<td style=\"width: 39px;text-align: center\">1156.80<\/td>\n<td style=\"width: 45px;text-align: center\">55<\/td>\n<\/p>\n<\/div>\n<\/div>\n<div>\n<div><span>Company Information<\/span><\/div>\n<div>\n<\/div>\n<\/div>\n<div>\n<div><span>Packaging &amp; Shipping<\/span><\/div>\n<div>\n<\/div>\n<\/div><\/div>\n<\/p><\/div>\n<div><\/div>\n<div><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n<div>\n<div><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div><\/div>\n<div><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div>","protected":false},"excerpt":{"rendered":"<p>Overview Quick Details Place of Origin: Shandong, China Brand Name: Haweisi Type: Fittings Product name: Flexible gear coupling Brand: Haweisi Warranty: 1 Year Package: Cartons or wooden cases Certificate: ISO9001:2015 Usage: connect screw and shaft Standard or Nonstandard: Standanrd(NL2-NL9) N0n-standard products: can be customized Supply Ability Supply Ability: 5000 Piece\/Pieces per Month Packaging &amp; Delivery [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[4],"class_list":["post-1979","post","type-post","status-publish","format-standard","hentry","category-gear-coupling","tag-db"],"_links":{"self":[{"href":"https:\/\/gear-coupling.top\/es\/wp-json\/wp\/v2\/posts\/1979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gear-coupling.top\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gear-coupling.top\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gear-coupling.top\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gear-coupling.top\/es\/wp-json\/wp\/v2\/comments?post=1979"}],"version-history":[{"count":0,"href":"https:\/\/gear-coupling.top\/es\/wp-json\/wp\/v2\/posts\/1979\/revisions"}],"wp:attachment":[{"href":"https:\/\/gear-coupling.top\/es\/wp-json\/wp\/v2\/media?parent=1979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gear-coupling.top\/es\/wp-json\/wp\/v2\/categories?post=1979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gear-coupling.top\/es\/wp-json\/wp\/v2\/tags?post=1979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}